{"id":468,"count":5,"description":"F\u0171szer: \u00e9telek \u00edzes\u00edt\u00e9s\u00e9hez haszn\u00e1lt anyag. Sz\u00e1mtalan fajt\u00e1juk ismert. Egy r\u00e9sz\u00fck haz\u00e1nkban is fellelhet\u0151, m\u00e1s r\u00e9sz\u00fcket - t\u00f6bbnyire T\u00e1vol-Keletr\u0151l - import\u00e1lni kell. H\u00e1rom csoportba oszthat\u00f3k:\r\n<ul>\r\n \t<li>levelek, magvak, gum\u00f3k, gy\u00f6kerek (sz\u00e1r\u00edtva, gyakran por\u00edtva)<\/li>\r\n \t<li>f\u0171szern\u00f6v\u00e9nyek (frissen vagy sz\u00e1r\u00edtva)<\/li>\r\n \t<li>\u00e1sv\u00e1nyi anyag: a s\u00f3.<\/li>\r\n<\/ul>","link":"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/fuszer\/","name":"F\u0171szer","slug":"fuszer","taxonomy":"category","parent":467,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u0171szer - k\u00fcl\u00f6nf\u00e9le, \u00edzes\u00edt\u00e9sre haszn\u00e1lt n\u00f6v\u00e9nyi r\u00e9szek - H\u00e1ztart\u00e1s Ma<\/title>\n<meta name=\"description\" content=\"F\u0171szer: k\u00fcl\u00f6nf\u00e9le n\u00f6v\u00e9nyi r\u00e9szek: levelek, vir\u00e1gok, magvak, gum\u00f3k, gy\u00f6kerek, fak\u00e9reg, citrusok h\u00e9ja friss vagy sz\u00e1r\u00edtott form\u00e1ban.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u0171szer - k\u00fcl\u00f6nf\u00e9le, \u00edzes\u00edt\u00e9sre haszn\u00e1lt n\u00f6v\u00e9nyi r\u00e9szek - H\u00e1ztart\u00e1s Ma\" \/>\n<meta property=\"og:description\" content=\"F\u0171szer: k\u00fcl\u00f6nf\u00e9le n\u00f6v\u00e9nyi r\u00e9szek: levelek, vir\u00e1gok, magvak, gum\u00f3k, gy\u00f6kerek, fak\u00e9reg, citrusok h\u00e9ja friss vagy sz\u00e1r\u00edtott form\u00e1ban.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/fuszer\/\" \/>\n<meta property=\"og:site_name\" content=\"H\u00e1ztart\u00e1s Ma\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/fuszer\/\",\"url\":\"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/fuszer\/\",\"name\":\"F\u0171szer - k\u00fcl\u00f6nf\u00e9le, \u00edzes\u00edt\u00e9sre haszn\u00e1lt n\u00f6v\u00e9nyi r\u00e9szek - H\u00e1ztart\u00e1s Ma\",\"isPartOf\":{\"@id\":\"https:\/\/www.haztartas-ma.hu\/#website\"},\"description\":\"F\u0171szer: k\u00fcl\u00f6nf\u00e9le n\u00f6v\u00e9nyi r\u00e9szek: levelek, vir\u00e1gok, magvak, gum\u00f3k, gy\u00f6kerek, fak\u00e9reg, citrusok h\u00e9ja friss vagy sz\u00e1r\u00edtott form\u00e1ban.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/fuszer\/#breadcrumb\"},\"inLanguage\":\"hu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/fuszer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.haztartas-ma.hu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u0171szerez\u00e9s\",\"item\":\"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"F\u0171szer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.haztartas-ma.hu\/#website\",\"url\":\"https:\/\/www.haztartas-ma.hu\/\",\"name\":\"H\u00e1ztart\u00e1s Ma\",\"description\":\"Egyszer\u0171 \u00e9telek, receptek, bef\u0151z\u00e9s, h\u00e1zi praktik\u00e1k\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.haztartas-ma.hu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u0171szer - k\u00fcl\u00f6nf\u00e9le, \u00edzes\u00edt\u00e9sre haszn\u00e1lt n\u00f6v\u00e9nyi r\u00e9szek - H\u00e1ztart\u00e1s Ma","description":"F\u0171szer: k\u00fcl\u00f6nf\u00e9le n\u00f6v\u00e9nyi r\u00e9szek: levelek, vir\u00e1gok, magvak, gum\u00f3k, gy\u00f6kerek, fak\u00e9reg, citrusok h\u00e9ja friss vagy sz\u00e1r\u00edtott form\u00e1ban.","robots":{"index":"noindex","follow":"follow"},"og_locale":"hu_HU","og_type":"article","og_title":"F\u0171szer - k\u00fcl\u00f6nf\u00e9le, \u00edzes\u00edt\u00e9sre haszn\u00e1lt n\u00f6v\u00e9nyi r\u00e9szek - H\u00e1ztart\u00e1s Ma","og_description":"F\u0171szer: k\u00fcl\u00f6nf\u00e9le n\u00f6v\u00e9nyi r\u00e9szek: levelek, vir\u00e1gok, magvak, gum\u00f3k, gy\u00f6kerek, fak\u00e9reg, citrusok h\u00e9ja friss vagy sz\u00e1r\u00edtott form\u00e1ban.","og_url":"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/fuszer\/","og_site_name":"H\u00e1ztart\u00e1s Ma","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/fuszer\/","url":"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/fuszer\/","name":"F\u0171szer - k\u00fcl\u00f6nf\u00e9le, \u00edzes\u00edt\u00e9sre haszn\u00e1lt n\u00f6v\u00e9nyi r\u00e9szek - H\u00e1ztart\u00e1s Ma","isPartOf":{"@id":"https:\/\/www.haztartas-ma.hu\/#website"},"description":"F\u0171szer: k\u00fcl\u00f6nf\u00e9le n\u00f6v\u00e9nyi r\u00e9szek: levelek, vir\u00e1gok, magvak, gum\u00f3k, gy\u00f6kerek, fak\u00e9reg, citrusok h\u00e9ja friss vagy sz\u00e1r\u00edtott form\u00e1ban.","breadcrumb":{"@id":"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/fuszer\/#breadcrumb"},"inLanguage":"hu"},{"@type":"BreadcrumbList","@id":"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/fuszer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.haztartas-ma.hu\/"},{"@type":"ListItem","position":2,"name":"F\u0171szerez\u00e9s","item":"https:\/\/www.haztartas-ma.hu\/index.php\/category\/fuszerezes\/"},{"@type":"ListItem","position":3,"name":"F\u0171szer"}]},{"@type":"WebSite","@id":"https:\/\/www.haztartas-ma.hu\/#website","url":"https:\/\/www.haztartas-ma.hu\/","name":"H\u00e1ztart\u00e1s Ma","description":"Egyszer\u0171 \u00e9telek, receptek, bef\u0151z\u00e9s, h\u00e1zi praktik\u00e1k","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haztartas-ma.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"}]}},"_links":{"self":[{"href":"https:\/\/www.haztartas-ma.hu\/index.php\/wp-json\/wp\/v2\/categories\/468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haztartas-ma.hu\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.haztartas-ma.hu\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.haztartas-ma.hu\/index.php\/wp-json\/wp\/v2\/categories\/467"}],"wp:post_type":[{"href":"https:\/\/www.haztartas-ma.hu\/index.php\/wp-json\/wp\/v2\/posts?categories=468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}